{"id":17467,"date":"2026-04-01T08:09:11","date_gmt":"2026-04-01T06:09:11","guid":{"rendered":"https:\/\/wipconsulting.it\/?p=17467"},"modified":"2026-03-30T19:29:17","modified_gmt":"2026-03-30T17:29:17","slug":"le-societa-straniere-in-delaware","status":"publish","type":"post","link":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/","title":{"rendered":"Le societ\u00e0 straniere in Delaware"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Il Delaware accoglie importanti gruppi operanti nei settori della finanza, della sanit\u00e0, della chimica e dell&#8217;istruzione universitaria, che annoverano la quasi totalit\u00e0 delle maggiori corporation americane e globali, le quali vi sono domiciliate &#8220;formalmente&#8221; per trarre vantaggio dal suo sistema legale. Tuttavia, \u00e8 fondamentale discernere tra i benefici per le societ\u00e0 con una sede operativa all&#8217;interno dello stato e quelle che vi hanno stabilito unicamente la propria sede legale (la celebre &#8220;Delaware corporation&#8221;).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ecco una panoramica delle principali aziende operanti in Delaware, suddivise per categoria:<\/span><\/p>\n<ol>\n<li><b>Aziende con Sede Legale in Delaware<\/b>: ono migliaia di societ\u00e0 incorporate in Delaware ma le cui operazioni, dirigenti e dipendenti sono sparsi in tutto il mondo. Ospita le sedi legali di numerosissime societ\u00e0 di comodo, soprattutto per vantaggi fiscali specifici. \u00c8 la categoria pi\u00f9 numerosa e significativa:\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Tecnologia: Apple Inc., Google (Alphabet Inc.), Microsoft, Meta Platforms (Facebook), Amazon (sebbene Amazon sia incorporata nello stato di Washington, molte sue controllate lo sono in Delaware), Oracle, Intel, Dell.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Finanza e investimenti: JPMorgan Chase (la holding), Goldman Sachs, Bank of America (la holding), Berkshire Hathaway (di Warren Buffett), The Vanguard Group, BlackRock.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Automotive e industria: General Motors (GM), Ford Motor Company, Tesla, Inc. (incorporata in Delaware fino al 2021, quando si \u00e8 spostata in Texas), Boeing (la holding), Caterpillar Inc.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Farmaceutica e chimica: Pfizer Inc., Johnson &amp; Johnson, Merck &amp; Co., DuPont de Nemours, Inc.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Media e intrattenimento: The Walt Disney Company, Comcast (NBC Universal), Viacom CBS (Paramount Global), News Corp, Twitter (al momento dell&#8217;incorporazione).<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Beni di consumo e retail: Walmart (la holding), The Coca-Cola Company, PepsiCo, Nike, Inc., McDonald&#8217;s Corporation, Walgreens Boots Alliance.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Energia: Exxon Mobil Corporation, Chevron Corporation, ConocoPhillips.<br \/>\n<\/span><\/li>\n<\/ul>\n<\/li>\n<li><b>Aziende con stabile presenza in loco<\/b>: s<span style=\"font-weight: 400;\">ono societ\u00e0 che hanno una significativa presenza fisica, come sedi operative, stabilimenti o quartieri generali, nello stato. Si citano:<\/span>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Chimica e scienze della Vita: DuPont (ha una lunga storia a Wilmington e ancora un quartier generale globale l\u00ec), Incyte (biofarmaceutica con HQ a Wilmington), Agilent Technologies (ha un importante sito a Wilmington).<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Finanza e servizi finanziari: Capital One (ha uno dei suoi principali campus e hub operativi a Wilmington, con migliaia di dipendenti), JPMorgan Chase (ha importanti operazioni di carte di credito e back-office nello stato), Bank of America (ha un importante centro operativo a Newark), Citizens Bank e M&amp;T Bank.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Servizi pubblici: Bloom Energy (ha un importante stabilimento di produzione a Newark).<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Agricoltura e allevamento: Perdue Farms (importante presenza nel settore avicolo, con stabilimenti nella contea di Sussex).<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Assicurazioni: Blue Cross Blue Shield of Delaware.\n<p><\/span><\/li>\n<\/ul>\n<\/li>\n<li><strong>Holding<\/strong>: m<span style=\"font-weight: 400;\">oltissime societ\u00e0, spesso di grandi gruppi nazionali e internazionali, hanno una sede formale (ad esempio, al numero 1209 North Orange Street di Wilmington, indirizzo noto per ospitare centinaia di migliaia di societ\u00e0) per gestire brevetti, propriet\u00e0 intellettuale o finanza strutturata. Queste raramente hanno dipendenti fisici nello stato. Le societ\u00e0 devono comunque presentare dichiarazioni annuali e pagare la franchise tax.\n<p><\/span><\/li>\n<\/ol>\n<p><strong><em style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji'; font-size: 16px;\">Contenuti protetti da copyright\u00a9. \u00c8 vietata la riproduzione, anche parziale, del testo con qualsiasi mezzo, senza autorizzazione.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Delaware accoglie importanti gruppi operanti nei settori della finanza, della sanit\u00e0, della chimica e dell&#8217;istruzione universitaria, che annoverano la quasi totalit\u00e0 delle maggiori corporation americane e globali, le quali vi sono domiciliate &#8220;formalmente&#8221; per trarre vantaggio dal suo sistema legale. Tuttavia, \u00e8 fondamentale discernere tra i benefici per le societ\u00e0 con una sede operativa [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":17469,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[39],"tags":[],"class_list":["post-17467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-globalcom"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le societ\u00e0 straniere in Delaware - WIP Consulting | Consulenza strategica<\/title>\n<meta name=\"description\" content=\"Delaware: hub di sedi legali per multinazionali e aziende globali, tra vantaggi fiscali e presenza operativa locale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le societ\u00e0 straniere in Delaware - WIP Consulting | Consulenza strategica\" \/>\n<meta property=\"og:description\" content=\"Delaware: hub di sedi legali per multinazionali e aziende globali, tra vantaggi fiscali e presenza operativa locale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/\" \/>\n<meta property=\"og:site_name\" content=\"WIP Consulting | Consulenza strategica\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-01T06:09:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/03\/Articolo-3-Le-societa-straniere.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"palumbo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"palumbo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/\"},\"author\":{\"name\":\"palumbo\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#\\\/schema\\\/person\\\/8de2db90898f864a55eadefdb8cc6e10\"},\"headline\":\"Le societ\u00e0 straniere in Delaware\",\"datePublished\":\"2026-04-01T06:09:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/\"},\"wordCount\":493,\"publisher\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Articolo-3-Le-societa-straniere.png\",\"articleSection\":[\"Globalcom\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/\",\"url\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/\",\"name\":\"Le societ\u00e0 straniere in Delaware - WIP Consulting | Consulenza strategica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Articolo-3-Le-societa-straniere.png\",\"datePublished\":\"2026-04-01T06:09:11+00:00\",\"description\":\"Delaware: hub di sedi legali per multinazionali e aziende globali, tra vantaggi fiscali e presenza operativa locale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Articolo-3-Le-societa-straniere.png\",\"contentUrl\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Articolo-3-Le-societa-straniere.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/le-societa-straniere-in-delaware\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le societ\u00e0 straniere in Delaware\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/\",\"name\":\"wipconsulting.it\",\"description\":\"Formazione alle imprese\",\"publisher\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#organization\",\"name\":\"WIP Consulting\",\"url\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo_wip_consulting_2colori_Registered_v02.svg\",\"contentUrl\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo_wip_consulting_2colori_Registered_v02.svg\",\"caption\":\"WIP Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#\\\/schema\\\/person\\\/8de2db90898f864a55eadefdb8cc6e10\",\"name\":\"palumbo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g\",\"caption\":\"palumbo\"},\"url\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/author\\\/palumbo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le societ\u00e0 straniere in Delaware - WIP Consulting | Consulenza strategica","description":"Delaware: hub di sedi legali per multinazionali e aziende globali, tra vantaggi fiscali e presenza operativa locale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/","og_locale":"en_US","og_type":"article","og_title":"Le societ\u00e0 straniere in Delaware - WIP Consulting | Consulenza strategica","og_description":"Delaware: hub di sedi legali per multinazionali e aziende globali, tra vantaggi fiscali e presenza operativa locale.","og_url":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/","og_site_name":"WIP Consulting | Consulenza strategica","article_published_time":"2026-04-01T06:09:11+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/03\/Articolo-3-Le-societa-straniere.png","type":"image\/png"}],"author":"palumbo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"palumbo","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/#article","isPartOf":{"@id":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/"},"author":{"name":"palumbo","@id":"https:\/\/wipconsulting.it\/en\/#\/schema\/person\/8de2db90898f864a55eadefdb8cc6e10"},"headline":"Le societ\u00e0 straniere in Delaware","datePublished":"2026-04-01T06:09:11+00:00","mainEntityOfPage":{"@id":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/"},"wordCount":493,"publisher":{"@id":"https:\/\/wipconsulting.it\/en\/#organization"},"image":{"@id":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/#primaryimage"},"thumbnailUrl":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/03\/Articolo-3-Le-societa-straniere.png","articleSection":["Globalcom"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/","url":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/","name":"Le societ\u00e0 straniere in Delaware - WIP Consulting | Consulenza strategica","isPartOf":{"@id":"https:\/\/wipconsulting.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/#primaryimage"},"image":{"@id":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/#primaryimage"},"thumbnailUrl":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/03\/Articolo-3-Le-societa-straniere.png","datePublished":"2026-04-01T06:09:11+00:00","description":"Delaware: hub di sedi legali per multinazionali e aziende globali, tra vantaggi fiscali e presenza operativa locale.","breadcrumb":{"@id":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/#primaryimage","url":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/03\/Articolo-3-Le-societa-straniere.png","contentUrl":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/03\/Articolo-3-Le-societa-straniere.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/wipconsulting.it\/en\/le-societa-straniere-in-delaware\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wipconsulting.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Le societ\u00e0 straniere in Delaware"}]},{"@type":"WebSite","@id":"https:\/\/wipconsulting.it\/en\/#website","url":"https:\/\/wipconsulting.it\/en\/","name":"wipconsulting.it","description":"Formazione alle imprese","publisher":{"@id":"https:\/\/wipconsulting.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wipconsulting.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wipconsulting.it\/en\/#organization","name":"WIP Consulting","url":"https:\/\/wipconsulting.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wipconsulting.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2023\/12\/logo_wip_consulting_2colori_Registered_v02.svg","contentUrl":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2023\/12\/logo_wip_consulting_2colori_Registered_v02.svg","caption":"WIP Consulting"},"image":{"@id":"https:\/\/wipconsulting.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wipconsulting.it\/en\/#\/schema\/person\/8de2db90898f864a55eadefdb8cc6e10","name":"palumbo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g","caption":"palumbo"},"url":"https:\/\/wipconsulting.it\/en\/author\/palumbo\/"}]}},"_links":{"self":[{"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/posts\/17467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/comments?post=17467"}],"version-history":[{"count":2,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/posts\/17467\/revisions"}],"predecessor-version":[{"id":17471,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/posts\/17467\/revisions\/17471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/media\/17469"}],"wp:attachment":[{"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/media?parent=17467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/categories?post=17467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/tags?post=17467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}