{"id":17733,"date":"2026-05-27T08:00:32","date_gmt":"2026-05-27T06:00:32","guid":{"rendered":"https:\/\/wipconsulting.it\/?p=17733"},"modified":"2026-05-26T15:46:39","modified_gmt":"2026-05-26T13:46:39","slug":"la-scommessa-del-piano-mattei","status":"publish","type":"post","link":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/","title":{"rendered":"La scommessa del Piano Mattei"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Il Piano Mattei, intitolato al fondatore dell&#8217;Eni Enrico Mattei, il quale promosse una politica di collaborazione paritetica tra le societ\u00e0 estrattive e i Paesi produttori di petrolio, rappresenta un&#8217;iniziativa politico-economica volta &#8220;alla costruzione di un nuovo partenariato tra Italia e Stati del Continente africano, mediante la promozione di uno sviluppo comune, sostenibile e duraturo nella dimensione politica, economica, sociale, culturale e di sicurezza&#8221;. Tale finalit\u00e0 \u00e8 stata sinteticamente esposta nella relazione al Decreto governativo, successivamente approvato dal Parlamento, convertito in Legge e pubblicato sulla Gazzetta Ufficiale in data 13 gennaio 2024.<\/span><\/p>\n<h6>Africa, crescita economica e demografica<\/h6>\n<p><span style=\"font-weight: 400;\">Sullo sfondo di questa iniziativa si colloca il rinnovato interesse dell\u2019Italia verso un Continente che, nonostante le sue criticit\u00e0, a volte drammatiche, rappresenta una delle aree con una crescita economica significativa (+ 3,9 % nel 2024; 4,1% nel 2025 e 4,3% nel 2026 secondo la Banca Africana di Sviluppo), caratterizzata da una demografia in notevole espansione (dagli attuali 1,3 miliardi di abitanti a 2,5 nel 2050) e ricchissima di materie prime fondamentali per molti processi industriali avanzati: litio, cobalto, platino, uranio, cromo, ecc., oltre a giacimenti di petrolio e gas. L&#8217;Italia si configura, anche in ragione della sua posizione geografica e delle peculiarit\u00e0 del suo tessuto economico, incentrato sulle PMI, quale partner naturale. Ciononostante, tale potenziale appare in larga misura inespresso se si considerano unicamente i valori dell&#8217;interscambio con i Paesi del Continente, che si attestano a 67 miliardi di Euro, di cui 45 miliardi di importazione (principalmente petrolio e gas) e 22 di esportazioni. Il dato assume tuttavia una valenza differente se si tiene conto che il nostro Paese si posiziona all&#8217;ottavo posto come fornitore e al quarto come acquirente del Continente.<\/span><\/p>\n<h6>La cabina di regia<\/h6>\n<p><span style=\"font-weight: 400;\">Ad oltre due anni dall&#8217;inizio della sua effettiva operativit\u00e0, si stanno definendo le relative modalit\u00e0 operative e il numero e la tipologia delle iniziative concretamente avviate. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">L&#8217;operativit\u00e0 del Piano \u00e8 demandata a una &#8220;Cabina di Regia&#8221;, presieduta dal Presidente del Consiglio Giorgia Meloni, con l&#8217;obiettivo di definire e attuare il Piano stesso. La \u201cCabina di Regia\u201d si riunisce con cadenza trimestrale. \u00c8 inoltre istituito un Ufficio (&#8220;Struttura di Missione&#8221;) presso la Presidenza del Consiglio, composto da personale proveniente da vari Ministeri e Organismi pubblici, in primo luogo dal Ministero degli Esteri. Questa struttura ha il compito di supportare la Cabina di Regia e di coordinare, a livello operativo, gli sforzi di tutte le articolazioni dello Stato, sia a livello centrale che territoriale, nonch\u00e9 della societ\u00e0 civile (Associazioni imprenditoriali e di categoria, Organizzazioni non Governative &#8211; OnG).<\/span><\/p>\n<h6>I finanziamenti<\/h6>\n<p><span style=\"font-weight: 400;\">Le risorse finanziarie assegnate al Piano ammontano a 5,3 miliardi di Euro, di cui 3,2 miliardi a carico dello stanziamento previsto per il Fondo Italiano per il Clima (FIC), destinato al finanziamento di progetti legati alla gestione del cambiamento climatico, e 2,1 miliardi di euro erogati da Cassa Depositi e Prestiti (CdP), il cui portafoglio include anche i Fondi destinati alla Cooperazione allo Sviluppo.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Come da intenzioni programmatiche, ai fondi nazionali si stanno gradualmente aggiungendo cofinanziamenti di Organismi Finanziari Multilaterali, in particolare quelli del programma dell&#8217;Unione Europea &#8220;Global Gateway Africa &#8211; Europe&#8221; per il finanziamento del corridoio di Lobito, quelli della Banca Europea degli Investimenti (BEI) e della Banca per la Ricostruzione e Sviluppo (BERS), oltre a quelli della Banca Mondiale. Quest&#8217;ultima, attraverso il suo braccio operativo per il settore privato, l&#8217;International Finance Corporation, che dispone di un ufficio permanente a Roma, partecipa a una &#8220;task force&#8221; finalizzata alla valutazione della fattibilit\u00e0 finanziaria di progetti nei Paesi africani. Ci\u00f2 avviene anche nell&#8217;ambito del Programma &#8220;Mission 300&#8221;, al quale aderisce anche l&#8217;Italia, che prevede la cooperazione tra la Banca Mondiale e la Banca Africana di Sviluppo per fornire accesso all&#8217;elettricit\u00e0 a 300 milioni di abitanti in Africa entro il 2030.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Contenuti protetti da copyright\u00a9. \u00c8 vietata la riproduzione, anche parziale, del testo con qualsiasi mezzo, senza autorizzazione.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Piano Mattei, intitolato al fondatore dell&#8217;Eni Enrico Mattei, il quale promosse una politica di collaborazione paritetica tra le societ\u00e0 estrattive e i Paesi produttori di petrolio, rappresenta un&#8217;iniziativa politico-economica volta &#8220;alla costruzione di un nuovo partenariato tra Italia e Stati del Continente africano, mediante la promozione di uno sviluppo comune, sostenibile e duraturo nella [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":17735,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[39],"tags":[],"class_list":["post-17733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-globalcom"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La scommessa del Piano Mattei - WIP Consulting | Consulenza strategica<\/title>\n<meta name=\"description\" content=\"Il Piano Mattei punta a rafforzare la cooperazione tra Italia e Africa con investimenti, sviluppo sostenibile e nuovi partenariati.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La scommessa del Piano Mattei - WIP Consulting | Consulenza strategica\" \/>\n<meta property=\"og:description\" content=\"Il Piano Mattei punta a rafforzare la cooperazione tra Italia e Africa con investimenti, sviluppo sostenibile e nuovi partenariati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/\" \/>\n<meta property=\"og:site_name\" content=\"WIP Consulting | Consulenza strategica\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-27T06:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/05\/Articolo-1-La-scommessa-del-Piano-Mattei.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"palumbo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"palumbo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/\"},\"author\":{\"name\":\"palumbo\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#\\\/schema\\\/person\\\/8de2db90898f864a55eadefdb8cc6e10\"},\"headline\":\"La scommessa del Piano Mattei\",\"datePublished\":\"2026-05-27T06:00:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/\"},\"wordCount\":618,\"publisher\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Articolo-1-La-scommessa-del-Piano-Mattei.png\",\"articleSection\":[\"Globalcom\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/\",\"url\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/\",\"name\":\"La scommessa del Piano Mattei - WIP Consulting | Consulenza strategica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Articolo-1-La-scommessa-del-Piano-Mattei.png\",\"datePublished\":\"2026-05-27T06:00:32+00:00\",\"description\":\"Il Piano Mattei punta a rafforzare la cooperazione tra Italia e Africa con investimenti, sviluppo sostenibile e nuovi partenariati.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Articolo-1-La-scommessa-del-Piano-Mattei.png\",\"contentUrl\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Articolo-1-La-scommessa-del-Piano-Mattei.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/la-scommessa-del-piano-mattei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La scommessa del Piano Mattei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/\",\"name\":\"wipconsulting.it\",\"description\":\"Formazione alle imprese\",\"publisher\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#organization\",\"name\":\"WIP Consulting\",\"url\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo_wip_consulting_2colori_Registered_v02.svg\",\"contentUrl\":\"https:\\\/\\\/wipconsulting.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo_wip_consulting_2colori_Registered_v02.svg\",\"caption\":\"WIP Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/#\\\/schema\\\/person\\\/8de2db90898f864a55eadefdb8cc6e10\",\"name\":\"palumbo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g\",\"caption\":\"palumbo\"},\"url\":\"https:\\\/\\\/wipconsulting.it\\\/en\\\/author\\\/palumbo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La scommessa del Piano Mattei - WIP Consulting | Consulenza strategica","description":"Il Piano Mattei punta a rafforzare la cooperazione tra Italia e Africa con investimenti, sviluppo sostenibile e nuovi partenariati.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/","og_locale":"en_US","og_type":"article","og_title":"La scommessa del Piano Mattei - WIP Consulting | Consulenza strategica","og_description":"Il Piano Mattei punta a rafforzare la cooperazione tra Italia e Africa con investimenti, sviluppo sostenibile e nuovi partenariati.","og_url":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/","og_site_name":"WIP Consulting | Consulenza strategica","article_published_time":"2026-05-27T06:00:32+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/05\/Articolo-1-La-scommessa-del-Piano-Mattei.png","type":"image\/png"}],"author":"palumbo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"palumbo","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/#article","isPartOf":{"@id":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/"},"author":{"name":"palumbo","@id":"https:\/\/wipconsulting.it\/en\/#\/schema\/person\/8de2db90898f864a55eadefdb8cc6e10"},"headline":"La scommessa del Piano Mattei","datePublished":"2026-05-27T06:00:32+00:00","mainEntityOfPage":{"@id":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/"},"wordCount":618,"publisher":{"@id":"https:\/\/wipconsulting.it\/en\/#organization"},"image":{"@id":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/#primaryimage"},"thumbnailUrl":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/05\/Articolo-1-La-scommessa-del-Piano-Mattei.png","articleSection":["Globalcom"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/","url":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/","name":"La scommessa del Piano Mattei - WIP Consulting | Consulenza strategica","isPartOf":{"@id":"https:\/\/wipconsulting.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/#primaryimage"},"image":{"@id":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/#primaryimage"},"thumbnailUrl":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/05\/Articolo-1-La-scommessa-del-Piano-Mattei.png","datePublished":"2026-05-27T06:00:32+00:00","description":"Il Piano Mattei punta a rafforzare la cooperazione tra Italia e Africa con investimenti, sviluppo sostenibile e nuovi partenariati.","breadcrumb":{"@id":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/#primaryimage","url":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/05\/Articolo-1-La-scommessa-del-Piano-Mattei.png","contentUrl":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2026\/05\/Articolo-1-La-scommessa-del-Piano-Mattei.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/wipconsulting.it\/en\/la-scommessa-del-piano-mattei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wipconsulting.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"La scommessa del Piano Mattei"}]},{"@type":"WebSite","@id":"https:\/\/wipconsulting.it\/en\/#website","url":"https:\/\/wipconsulting.it\/en\/","name":"wipconsulting.it","description":"Formazione alle imprese","publisher":{"@id":"https:\/\/wipconsulting.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wipconsulting.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wipconsulting.it\/en\/#organization","name":"WIP Consulting","url":"https:\/\/wipconsulting.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wipconsulting.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2023\/12\/logo_wip_consulting_2colori_Registered_v02.svg","contentUrl":"https:\/\/wipconsulting.it\/wp-content\/uploads\/2023\/12\/logo_wip_consulting_2colori_Registered_v02.svg","caption":"WIP Consulting"},"image":{"@id":"https:\/\/wipconsulting.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wipconsulting.it\/en\/#\/schema\/person\/8de2db90898f864a55eadefdb8cc6e10","name":"palumbo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/493654915231df341dbf19a0af4e4d667d639ce2a66582f1c6e9fdd2ae0fa99e?s=96&d=mm&r=g","caption":"palumbo"},"url":"https:\/\/wipconsulting.it\/en\/author\/palumbo\/"}]}},"_links":{"self":[{"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/posts\/17733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/comments?post=17733"}],"version-history":[{"count":3,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/posts\/17733\/revisions"}],"predecessor-version":[{"id":17744,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/posts\/17733\/revisions\/17744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/media\/17735"}],"wp:attachment":[{"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/media?parent=17733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/categories?post=17733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wipconsulting.it\/en\/wp-json\/wp\/v2\/tags?post=17733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}